{"id":309,"count":1,"description":"","link":"https:\/\/shafaclinicetd.com\/en\/tag\/is-malignant-prostate-cancer-fatal\/","name":"Is malignant prostate cancer fatal?","slug":"is-malignant-prostate-cancer-fatal","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.0 (Yoast SEO v24.9) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Is malignant prostate cancer fatal? | Shafa Radiotherapy Oncology Center<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/shafaclinicetd.com\/en\/tag\/is-malignant-prostate-cancer-fatal\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Is malignant prostate cancer fatal?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/shafaclinicetd.com\/en\/tag\/is-malignant-prostate-cancer-fatal\/\" \/>\n<meta property=\"og:site_name\" content=\"Shafa Radiotherapy Oncology Center\" \/>\n<meta property=\"og:image\" content=\"https:\/\/shafaclinicetd.com\/wp-content\/uploads\/2024\/09\/1969999.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"866\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/shafaclinicetd.com\/en\/tag\/is-malignant-prostate-cancer-fatal\/\",\"url\":\"https:\/\/shafaclinicetd.com\/en\/tag\/is-malignant-prostate-cancer-fatal\/\",\"name\":\"Is malignant prostate cancer fatal? | Shafa Radiotherapy Oncology Center\",\"isPartOf\":{\"@id\":\"https:\/\/shafaclinicetd.com\/en\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/shafaclinicetd.com\/en\/tag\/is-malignant-prostate-cancer-fatal\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/shafaclinicetd.com\/en\/tag\/is-malignant-prostate-cancer-fatal\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u062e\u0627\u0646\u0647\",\"item\":\"https:\/\/shafaclinicetd.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Is malignant prostate cancer fatal?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/shafaclinicetd.com\/en\/#website\",\"url\":\"https:\/\/shafaclinicetd.com\/en\/\",\"name\":\"\u0645\u0631\u06a9\u0632 \u0631\u0627\u062f\u06cc\u0648\u062a\u0631\u0627\u067e\u06cc \u0622\u0646\u06a9\u0648\u0644\u0648\u0698\u06cc \u0634\u0641\u0627\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/shafaclinicetd.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/shafaclinicetd.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/shafaclinicetd.com\/en\/#organization\",\"name\":\"Shafa Radiotherapy Oncology Center\",\"url\":\"https:\/\/shafaclinicetd.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/shafaclinicetd.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/shafaclinicetd.com\/wp-content\/uploads\/2024\/09\/logoshafa.webp\",\"contentUrl\":\"https:\/\/shafaclinicetd.com\/wp-content\/uploads\/2024\/09\/logoshafa.webp\",\"width\":340,\"height\":60,\"caption\":\"Shafa Radiotherapy Oncology Center\"},\"image\":{\"@id\":\"https:\/\/shafaclinicetd.com\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Is malignant prostate cancer fatal? | Shafa Radiotherapy Oncology Center","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/shafaclinicetd.com\/en\/tag\/is-malignant-prostate-cancer-fatal\/","og_locale":"en_US","og_type":"article","og_title":"Is malignant prostate cancer fatal?","og_url":"https:\/\/shafaclinicetd.com\/en\/tag\/is-malignant-prostate-cancer-fatal\/","og_site_name":"Shafa Radiotherapy Oncology Center","og_image":[{"width":866,"height":1000,"url":"https:\/\/shafaclinicetd.com\/wp-content\/uploads\/2024\/09\/1969999.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/shafaclinicetd.com\/en\/tag\/is-malignant-prostate-cancer-fatal\/","url":"https:\/\/shafaclinicetd.com\/en\/tag\/is-malignant-prostate-cancer-fatal\/","name":"Is malignant prostate cancer fatal? | Shafa Radiotherapy Oncology Center","isPartOf":{"@id":"https:\/\/shafaclinicetd.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/shafaclinicetd.com\/en\/tag\/is-malignant-prostate-cancer-fatal\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/shafaclinicetd.com\/en\/tag\/is-malignant-prostate-cancer-fatal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u062e\u0627\u0646\u0647","item":"https:\/\/shafaclinicetd.com\/en\/"},{"@type":"ListItem","position":2,"name":"Is malignant prostate cancer fatal?"}]},{"@type":"WebSite","@id":"https:\/\/shafaclinicetd.com\/en\/#website","url":"https:\/\/shafaclinicetd.com\/en\/","name":"\u0645\u0631\u06a9\u0632 \u0631\u0627\u062f\u06cc\u0648\u062a\u0631\u0627\u067e\u06cc \u0622\u0646\u06a9\u0648\u0644\u0648\u0698\u06cc \u0634\u0641\u0627","description":"","publisher":{"@id":"https:\/\/shafaclinicetd.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/shafaclinicetd.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/shafaclinicetd.com\/en\/#organization","name":"Shafa Radiotherapy Oncology Center","url":"https:\/\/shafaclinicetd.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/shafaclinicetd.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/shafaclinicetd.com\/wp-content\/uploads\/2024\/09\/logoshafa.webp","contentUrl":"https:\/\/shafaclinicetd.com\/wp-content\/uploads\/2024\/09\/logoshafa.webp","width":340,"height":60,"caption":"Shafa Radiotherapy Oncology Center"},"image":{"@id":"https:\/\/shafaclinicetd.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/shafaclinicetd.com\/en\/wp-json\/wp\/v2\/tags\/309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shafaclinicetd.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/shafaclinicetd.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/shafaclinicetd.com\/en\/wp-json\/wp\/v2\/posts?tags=309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}